{"id":1071,"date":"2024-04-06T21:39:00","date_gmt":"2024-04-06T19:39:00","guid":{"rendered":"https:\/\/urbexplorer.net\/?page_id=1071"},"modified":"2025-08-19T00:27:02","modified_gmt":"2025-08-18T22:27:02","slug":"cookie-policy","status":"publish","type":"page","link":"https:\/\/urbexplorer.net\/it\/cookie-policy\/","title":{"rendered":"Informativa sui cookie"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1071\" class=\"elementor elementor-1071\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a766d6 e-flex e-con-boxed e-con e-parent\" data-id=\"2a766d6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4d8e61 elementor-widget elementor-widget-heading\" data-id=\"b4d8e61\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Informativa sui cookie<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7a7a5b elementor-widget elementor-widget-shortcode\" data-id=\"e7a7a5b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Questa politica sui cookie \u00e8 stata aggiornata l'ultima volta il 10. Gennaio 2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.<\/i><br><\/p><h2>1. Introduzione<\/h2><p>Il nostro sito web,<a href=\"https:\/\/urbexplorer.net\/it\">https:\/\/urbexplorer.net\/it<\/a> (di seguito: \"il sito web\") utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite \"cookie\"). I cookie vengono anche inseriti da terze parti che abbiamo ingaggiato. Nel documento sottostante ti informiamo sull'uso dei cookie sul nostro sito web.<\/p><h2>2. Cosa sono i cookie?<\/h2><p>I cookie sono dei semplici file spediti assieme alle pagine di questo sito e salvati dal tuo browser sul disco rigido del tuo computer o altri dispositivi. Le informazioni raccolte in essi possono venire rispedite ai nostri server oppure ai server di terze parti durante la prossima visita.<\/p><h2>3. Cosa sono gli script?<\/h2><p>Uno script \u00e8 un pezzo di codice usato per far funzionare correttamente ed interattivamente il nostro sito. Questo codice viene eseguito sui nostri server o sul tuo dispositivo.<\/p><h2>4. Cos'\u00e8 un web beacon?<\/h2><p>Un web beacon (o pixel tag) \u00e8 un piccolo, invisibile pezzo di testo o immagine su un sito che viene usato per monitorare il traffico di un sito web. Per fare questo, diversi dati su di te vengono conservati utilizzando dei web beacon.<\/p><h2>5. Biscotto<\/h2><p class=\"cmplz-subtitle\">5.1 Cookie tecnici o funzionali<\/p><p>Alcuni cookie assicurano il corretto funzionamento del sito e che le tue preferenze rimangano valide. Piazzando i cookie funzionali, rendiamo pi\u00f9 facile per te visitare il nostro sito web. In questo modo non devi inserire ripetutamente le stesse informazioni quando visiti il nostro sito web, per esempio, l'oggetto rimane nel tuo carrello finch\u00e9 non hai pagato. Possiamo piazzare questi cookie senza il tuo consenso.<\/p><p class=\"cmplz-subtitle\">5.2 Cookie statistici<\/p><p>Utilizziamo i cookie statistici per ottimizzare l'esperienza del sito web per i nostri utenti. Con questi cookie statistici otteniamo approfondimenti sull'uso del nostro sito web. Chiediamo il tuo permesso per piazzare i cookie statistici.<\/p><p class=\"cmplz-subtitle\">5.3 Cookie pubblicitari<\/p><p>Su questo sito utilizziamo cookie per gli annunci, permettendoci di personalizzare gli annunci per te, e noi (e terze parti) abbiamo accesso ai risultati della campagna. Questo accade in base al profilo che abbiamo creato basato sui tuoi click e la navigazione nel ed al di fuori di <a href=\"https:\/\/urbexplorer.net\/it\">https:\/\/urbexplorer.net\/it<\/a>. Con questo cookie tu, come visitatore del sito, vieni collegato ad un ID univoco, cos\u00ec da non vedere le stesse cose per pi\u00f9 di una volta per esempio.<\/p><p class=\"cmplz-subtitle\">5.4 Cookie di marketing\/tracciamento<\/p><p>I cookie di marketing\/tracciamento sono cookie o qualsiasi altra forma di memorizzazione locale, utilizzati per creare profili utente per visualizzare pubblicit\u00e0 o per tracciare l'utente su questo sito web o su diversi siti web per scopi di marketing simili.<\/p><p>Visto che questi cookie sono segnalati come cookie traccianti, ti chiediamo il permesso di piazzarli.<\/p><p class=\"cmplz-subtitle\">5.5 I social media<\/p><p>Sul nostro sito web abbiamo inserito contenuti di Facebook, Instagram e TikTok per promuovere pagine web (ad es. \"mi piace\", \"pin\") o condividerle (ad es. \"tweet\") su social network come Facebook, Instagram e TikTok. Questo contenuto \u00e8 incorporato con codice derivato da Facebook, Instagram e TikTok e inserisce cookie. Questo contenuto potrebbe memorizzare ed elaborare alcune informazioni per la pubblicit\u00e0 personalizzata.<\/p><p>Leggi l'informativa sulla privacy di questi social network (che possono cambiare regolarmente) per sapere cosa fanno con i tuoi dati (personali) che elaborano usando questi cookie. I dati ottenuti vengono anonimizzati quanto possibile. Facebook, Instagram e TikTok si trovano negli Stati Uniti.<\/p><h2>6. Cookie presenti<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Elementor<\/h3>\n\t\t<p>Statistiche (anonimo)<\/p>\n\t\t<label for=\"cmplz_service_elementor\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio o<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_elementor\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"elementor\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Elementor per la creazione di contenuti. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/elementor\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiche (anonimo)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/elementor\/elementor\/\">elemento<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le azioni compiute dall'utente sul sito web<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">mappa-termini<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Pubblicit\u00e0<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Google reCAPTCHA per prevenire lo spam. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-recaptcha\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google reCAPTCHA Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/_grecaptcha\/\">_grecaptcha<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcc\/\">rc::c<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Filtra richieste dei bot<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcb\/\">rc::b<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Filtra richieste dei bot<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rca\/\">rc::a<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Filtra richieste dei bot<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Elementor<\/h3>\n\t\t<p>Scopo in attesa di indagine<\/p>\n\t\t<label for=\"cmplz_service_elementor\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio o<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_elementor\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"elementor\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Elementor per creare contenuti. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/elementor\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">pedro-mode<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Atlassian Jira Servicedesk<\/h3>\n\t\t<p>Statistiche<\/p>\n\t\t<label for=\"cmplz_service_atlassian-jira-servicedesk\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio atlassian-jira-servicedesk<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_atlassian-jira-servicedesk\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"atlassian-jira-servicedesk\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Atlassian Jira Servicedesk per la gestione del supporto utente. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/atlassian-jira-servicedesk\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiche<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/atlassian-jira-servicedesk\/ajs_anonymous_id\/\">ajs_anonymous_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 anno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare l'ultima visita<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>CloudFlare<\/h3>\n\t\t<p>Funzionale<\/p>\n\t\t<label for=\"cmplz_service_cloudflare\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio cloudflare<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_cloudflare\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"cloudflare\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo CloudFlare per servizi di content distribution network (CDN). <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/cloudflare\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.cloudflare.com\/privacypolicy\">CloudFlare Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/cloudflare\/__cf_bm\/\">__cf_bm<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">30 minuti<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Filtra richieste dei bot<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>GeoDirectory<\/h3>\n\t\t<p>Funzionale<\/p>\n\t\t<label for=\"cmplz_service_geodirectory\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio geodirectory<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_geodirectory\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"geodirectory\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo GeoDirectory per la pubblicit\u00e0. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/geodirectory\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/geodirectory\/gd_recently_viewed\/\">gd_recentemente_visto<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Fornisce una funzionalit\u00e0 di visualizzazione persistente degli elementi<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Funzionale<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo WordPress per lo sviluppo del sito web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsSupports<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare i dettagli del browser<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp_lang\/\">wp_lang<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-impostazioni-tempo-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>A strisce<\/h3>\n\t\t<p>Scopo in attesa di indagine<\/p>\n\t\t<label for=\"cmplz_service_stripe\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso alla striscia di servizio<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_stripe\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"stripe\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Stripe per la gestione dei pagamenti. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/stripe\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/stripe.com\/privacy\/\">Stripe Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/stripe\/__stripe_mid\/\">__stripe_mid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/stripe\/__stripe_sid\/\">__stripe_sid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WPML<\/h3>\n\t\t<p>Funzionale<\/p>\n\t\t<label for=\"cmplz_service_wpml\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio wpml<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpml\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wpml\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo WPML per la gestione della lingua. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wpml\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wpml\/wp-wpml_current_language\/\">wp-wpml_current_language<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 giorno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le impostazioni della lingua<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Analytics<\/h3>\n\t\t<p>Statistiche<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio google-analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Google Analytics per le statistiche del sito web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-analytics\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google Analytics Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga\/\">_ga<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiche<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga_\/\">_ga_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 anno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Conta e traccia le visualizzazioni delle pagine<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>poeta della posta<\/h3>\n\t\t<p>Scopo in attesa di indagine<\/p>\n\t\t<label for=\"cmplz_service_mailpoet\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio mailpoet<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_mailpoet\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"mailpoet\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo mailpoet per sottoscrivere alle email. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/mailpoet\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/automattic.com\/privacy\/\">mailpoet Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/mailpoet\/mailpoet_page_view\/\">pagina_mailpoet_view<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Pubblicit\u00e0<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Google Fonts per mostrare i webfont. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Fonts Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-fonts\/tcb_google_fonts\/\">Google Fonts API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">nessuno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Richiedere l'indirizzo IP dell'utente<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Pubblicit\u00e0<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Google Maps per mappare i display. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-maps\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google Maps Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-maps\/google-maps-api\/\">API di Google Maps<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">nessuno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Richiedere l'indirizzo IP dell'utente<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Pubblicit\u00e0<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio youtube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo YouTube per mostrare video. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">YouTube Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/gps\/\">GPS<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare i dati di posizione<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/visitor_info1_live\/\">VISITATORE_INFO1_LIVE<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">6 mesi<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Abilita la consegna di annunci o retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/ysc\/\">YSC<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Memorizza e traccia le interazioni<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/pref\/\">PREF<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">8 mesi<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze dell'utente<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Facebook<\/h3>\n\t\t<p>Pubblicit\u00e0, Funzionale<\/p>\n\t\t<label for=\"cmplz_service_facebook\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio facebook<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_facebook\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"facebook\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Facebook per mostrare i post social recenti e\/o i pulsanti di condivisione. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/facebook\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/policy\/cookies\">Facebook Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbc\/\">_fbc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">2 anni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare l'ultima visita<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fbm_\/\">fbm*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 anno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare i dettagli utente<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/xs\/\">xs<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">3 mesi<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare un ID sessione univoco<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fr\/\">fr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">3 mesi<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Abilita la consegna di annunci o retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/act\/\">atto<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">90 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Mantieni l'accesso degli utenti<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbp\/\">_fbp<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">3 mesi<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare e tracciare le visite attraverso i siti web<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/datr\/\">datr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">2 anni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Fornisce la prevenzione delle frodi<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/c_user\/\">c_utente<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">30 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare un ID utente univoco<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/sb\/\">cpv.<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">2 anni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare i dettagli del browser<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbm_\/\">*_fbm_<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 anno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare i dettagli utente<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/wd\/\">wd<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 settimana<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Determina la risoluzione dello schermo<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/csm\/\">csm<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">90 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Fornisce la prevenzione delle frodi<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/actppresence\/\">attoppresenza<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare e tracciare se la scheda del browser \u00e8 attiva<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>TikTok<\/h3>\n\t\t<p>Pubblicit\u00e0, Funzionale<\/p>\n\t\t<label for=\"cmplz_service_tiktok\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio tiktok<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_tiktok\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"tiktok\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo TikTok per mostrare video. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/tiktok\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.tiktok.com\/legal\/privacy-policy\">TikTok Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/s_v_web_id\/\">s_v_web_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare se l'utente ha visto un contenuto incorporato<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/auto-draft-10\/\">ID_WEB_ MONITOR<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">3 mesi<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare se l'utente ha visto un contenuto incorporato<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/tt_webid\/\">tt_webid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 anno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare se l'utente ha visto un contenuto incorporato<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/tt_webid_v2\/\">tt_webid_v2<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 anno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare se l'utente ha visto un contenuto incorporato<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/ttwid\/\">ttwid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 anno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare se l'utente ha visto un contenuto incorporato<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp_launch_mode\/\">webapp_launch_mode<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare se l'utente ha visto un contenuto incorporato<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp_session_id\/\">webapp_session_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare un ID sessione univoco<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp-session-referer\/\">webapp-session-referer<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare sito web di riferimento<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp_tiktok_privious\/\">webapp_tiktok_privious<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare se l'utente ha visto un contenuto incorporato<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp_extra_data\/\">webapp_extra_data<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Fornisce funzioni attraverso diverse pagine<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/auto-draft-7\/\">tipo_traffico_originale_webapp<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare se l'utente ha visto un contenuto incorporato<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/guide-login-config\/\">guida-login-config<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare un ID utente univoco<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/__tea_cache_tokens_\/\">__tea_cache_tokens_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare un ID sessione univoco<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/csrf_session_id\/\">csrf_session_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Fornisce protezione contro gli hacker<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/auto-draft-9\/\">tt_csrf_token<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Fornisce protezione contro gli hacker<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/_abck\/\">_abck<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 anno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Fornisce protezione contro gli hacker<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/__tea_cache_first_\/\">__tea_cache_first_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Caricare le funzionalit\u00e0 di bilanciamento<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp-newuser\/\">webapp-newuser<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare la prima visita al sito<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/autoplay-config\/\">configurazione autoplay<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Configurazione negozio<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp-video-mute\/\">webapp-video-mute<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Configurazione negozio<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/f\/\">f<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/__tt_embed__mounting\/\">__tt_embed__mounting<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/__tt_embed__storage_test\/\">__tt_embed__storage_test<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Funzionale<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio complianz<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Complianz per la gestione del consenso ai cookie. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/complianz\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti. Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">Adempiere alla Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_functional\/\">cmplz_funzionale<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_statistics\/\">cmplz_statistics<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_preferences\/\">cmplz_preferences<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_marketing\/\">cmplz_marketing<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_saved_services\/\">cmplz_saved_services<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_id\/\">cmplz_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_consented_services\/\">cmplz_consented_services<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_policy_id\/\">cmplz_policy_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Registra l'ID della cookie policy accettata<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_banner-status\/\">cmplz_banner-status<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Memorizza se il banner dei cookie \u00e8 stato eliminato<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_saved_categories\/\">cmplz_saved_categories<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_user_data\/\">cmplz_user_data<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Determina quale banner dei cookie mostrare<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Servizi vari di Google<\/h3>\n\t\t<p>Funzionale<\/p>\n\t\t<label for=\"cmplz_service_google-various-services\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio google-various-services<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-various-services\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-various-services\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo i vari servizi di Google per lo sviluppo del sito web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-various-services\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google vari servizi Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-various-services\/google_auto_fc_cmp_setting\/\">google_auto_fc_cmp_setting<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Mixpanel<\/h3>\n\t\t<p>Scopo in attesa di indagine<\/p>\n\t\t<label for=\"cmplz_service_mixpanel\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consenso al servizio mixpanel<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_mixpanel\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"mixpanel\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Mixpanel per le statistiche del sito web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/mixpanel\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/mixpanel.com\/legal\/privacy-policy\/\">Mixpanel Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">*_mixpanel<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Varie<\/h3>\n\t\t<p>Scopo in attesa di indagine<\/p>\n\t\t<label for=\"cmplz_service_varie\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Il consenso al servizio varia<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_varie\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"varie\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>La condivisione dei dati \u00e8 in attesa di indagine<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">e_kit-elements-defaults<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wpc\/\">wpc*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">livello di log<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">__darkreader__wasEnabledForHost<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">quads_browser_width<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/_gd_logged_out_post_author\/\">_gd_logged_out_post_author<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cookie s\u00ec-consenso<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">bp-membri-scopo<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">fp_logged_in_roles<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_consent_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">urbexplorer.net<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_consent_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">urbexplorer.net<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_consent_statistics-anonymous<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">urbexplorer.net<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_consent_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">urbexplorer.net<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_consent_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">urbexplorer.net<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">ambienteCategorie-4<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">awc.ui.viewed.last.sent<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">categorie d'uso mensili-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">categorie d'uso mensili-3<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">categorie d'uso mensili-7<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">categorie d'uso mensili-2<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">awc.session.id<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">Categorie d'uso mensili<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">categorie d'uso mensili-8<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">Categorie d'uso mensili-6<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">ambienteCategorie-3<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">awc.session.expiry<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">categorie d'uso mensili-4<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">categorie d'uso mensili-0<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">ambienteCategorie<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">mwai_settings_section<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">Categorie d'uso mensili-5<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">tooltipPause<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">filtro bp-attivit\u00e0<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">bp-activity-scope<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">mwai_session_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cf_clearance<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">impostazioni_adsense<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">__eoi<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_tcf_consenso<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_ac_stringa<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">__gads<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">__gpi<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consensi<\/h2><p>Quando visiti il sito web per la prima volta, mostreremo un popup con una spiegazione dei cookie. Appena clicchi su \"Salva preferenze\", dai il permesso a noi di usare le categorie di cookie e plugin come descritto in questa dichiarazione relativa ai popup e cookie. Puoi disabilitare i cookie attraverso il tuo browser, ma prendi in considerazione, che il nostro sito web potrebbe non funzionare pi\u00f9 correttamente.<\/p><p class=\"cmplz-subtitle\">7.1 Gestisci le tue impostazioni di consenso<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Hai caricato la Cookie Policy senza supporto javascript. Su AMP, puoi usare il pulsante di gestione del consenso in fondo alla pagina.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><p class=\"cmplz-subtitle\">7.2 Fornitori<\/p><div id=\"cmplz-tcf-wrapper-nojavascript\">L'elenco dei fornitori TCF non \u00e8 disponibile quando JavaScript \u00e8 disabilitato, come su AMP.<\/div>\n<div id=\"cmplz-tcf-wrapper\">\n\t<div id=\"cmplz-tcf-buttons-template\">\n\t\t<div class=\"cmplz-tcf-buttons\">\n\t\t\t<button id=\"cmplz-tcf-selectall\">Seleziona tutto<\/button>\n\t\t\t<button id=\"cmplz-tcf-deselectall\">Deseleziona tutti<\/button>\n\t\t<\/div>\n\t<\/div>\n\t<div id=\"cmplz-tcf-vendor-template\" class=\"cmplz-tcf-template\"><div class=\"cmplz-tcf-vendor-container cmplz-tcf-optin cmplz-tcf-checkbox-container\">\n\t<label for=\"cmplz-tcf-vendor-{vendor_id}\">\n\t\t<input id=\"cmplz-tcf-{vendor_id}\" class=\"cmplz-tcf-vendor-input\" value=\"1\" type=\"checkbox\" name=\"cmplz-tcf-vendor-{vendor_id}\">\n\t\t{nome_venditore}\n\t\t<div class=\"cmplz-vendortype-label\">Fornitore non-TCF<\/div>\n\t\t<a href=\"#\" class=\"cmplz-tcf-toggle-vendor cmplz-tcf-rm\"><\/a>\n\t<\/label>\n\t<div class=\"cmplz-tcf-links\">\n\t\t<div class=\"cmplz-tcf-policy-url\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"\/it\/{privacy_policy}\/\">Informativa sulla privacy<\/a><\/div>\n\t<\/div>\n\t<div class=\"cmplz-tcf-info\">\n\t\t<div class=\"cmplz-tcf-info-content\">\n\t\t\t<div class=\"cmplz-tcf-header\">Basi legali<\/div>\n\t\t\t<div class=\"cmplz-tcf-description\">\n\t\t\t\t<label for=\"consent_{vendor_id}\">\n\t\t\t\t\t<input type=\"checkbox\" name=\"consent_{vendor_id}\" class=\"cmplz-tcf-consent-input\">\n\t\t\t\t\t<a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/tcf\/consent\">Consenso<\/a>\n\t\t\t\t<\/label>\n\t\t\t\t<label for=\"legitimate_interest_{vendor_id}\" class=\"cmplz_tcf_legitimate_interest_checkbox\">\n\t\t\t\t\t<input type=\"checkbox\" name=\"legitimate_interest_{vendor_id}\" class=\"cmplz-tcf-legitimate-interest-input\">\n\t\t\t\t\t<a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/tcf\/legitimate-interest\">Legittimo Interesse<\/a>\n\t\t\t\t<\/label>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"cmplz-tcf-info-content\">\n\t\t\t<div class=\"cmplz-tcf-header\">Scadenza massima dei cookie:<\/div>\n\t\t\t<div class=\"cmplz-tcf-description\">&nbsp;\n\t\t\t\t<span class=\"session-storage\">Archivio della sessione<\/span>\n\t\t\t\t<span class=\"retention_days\">{cookie_retention_days} giorni<\/span>\n\t\t\t\t<span class=\"retention_seconds\">{cookie_retention_seconds} secondi<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"cmplz-tcf-info-content\">\n\t\t\t<div class=\"cmplz-tcf-header\">Archivio non-cookie e accesso:<\/div>\n\t\t\t<div class=\"cmplz-tcf-description\">&nbsp;<span class=\"non-cookie-storage-active\">S\u00ec<\/span>\n\t\t\t\t<span class=\"non-cookie-storage-inactive\">No<\/span><\/div>\n\t\t<\/div>\n\t\t<div class=\"cmplz-tcf-info-content\">\n\t\t\t<div class=\"cmplz-tcf-header\">Aggiornamento dei cookie:<\/div>\n\t\t\t<div class=\"cmplz-tcf-description\">&nbsp;<span class=\"non-cookie-refresh-active\">S\u00ec<\/span>\n\t\t\t\t<span class=\"non-cookie-refresh-inactive\">No<\/span><\/div>\n\t\t<\/div>\n\t\t<div class=\"cmplz-tcf-info-content\">\n\t\t\t<div class=\"cmplz-tcf-header\">Categorie:<\/div>\n\t\t\t<div class=\"cmplz-tcf-description\">{categorie_venditori}<\/div>\n\t\t<\/div>\n\t\t<div class=\"cmplz-tcf-info-content\">\n\t\t\t<div class=\"cmplz-tcf-header\">Scopi<\/div>\n\t\t\t<div class=\"cmplz-tcf-description\">{purpose}<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t<div id=\"cmplz-tcf-type-template\" class=\"cmplz-tcf-template\"><div class=\"cmplz-tcf-{type}-container cmplz-tcf-checkbox-container\">\n\t<label for=\"cmplz-tcf-{type}-{type_id}\">\n\t\t<input id=\"cmplz-tcf-{type}-{type_id}\" class=\"cmplz-tcf-{type}-input cmplz-tcf-input\" value=\"1\" type=\"checkbox\" name=\"cmplz-tcf-{type}-{type_id}\">\n\t\t{nome_tipo} | Utilizzato da {type_count} fornitori<a href=\"#\" class=\"cmplz-tcf-toggle cmplz-tcf-rm\"><\/a>\n\t\t<div id=\"cmplz-tcf-{type}-{type_id}-desc\" class=\"cmplz-tcf-type-description\">\n\t\t\t<div class=\"cmplz-tcf-type-desc__text\">{type_description}<\/div>\n\t\t\t<div class=\"cmplz-tcf-type-desc__example-title\">Esempio<\/div>\n\t\t\t<div class=\"cmplz-tcf-type-desc__example\">{tipo_esempio}<\/div>\n\t\t<\/div>\n\n\t\t<div id=\"cmplz-tcf-{type}-{type_id}-desc\" class=\"cmplz-tcf-type-description\">{type_description}<\/div>\n\t<\/label>\n<\/div>\n<\/div>\n\t<p>Questi sono i partner con cui condividiamo i dati. Cliccando su ogni partner, si pu\u00f2 vedere per quali scopi stanno richiedendo il consenso e\/o per quali scopi stanno rivendicando un interesse legittimo.<\/p>\n\t<p>\u00c8 possibile fornire o ritirare il consenso, e opporsi agli scopi di legittimo interesse per il trattamento dei dati personali. Tuttavia, si prega di notare che disabilitando l'elaborazione di tutti i dati, alcune funzionalit\u00e0 del sito potrebbero essere influenzate.<\/p>\n\t<p class=\"cmplz-subtitle\">7.2.1 Consenso<\/p>\n\t<p>Qui di seguito potete dare e ritirare il vostro consenso in base allo scopo.<\/p>\n\t<b>Statistiche<\/b>\n\t<p id=\"cmplz-tcf-statistics-purpose_consents-container\" class=\"cmplz-tcf-container\"><\/p>\n\t<b>Marketing<\/b>\n\t<p id=\"cmplz-tcf-marketing-purpose_consents-container\" class=\"cmplz-tcf-container\"><\/p>\n\n\t<p class=\"cmplz-subtitle\">7.2.2 Legittimo Interesse<\/p>\n\t<p>Alcuni venditori fissano degli scopi con interesse legittimo, una base legale secondo il GDPR per il trattamento dei dati. Hai il \"Diritto di opposizione\" a questo trattamento dei dati e puoi farlo in seguito per ogni scopo.<\/p>\n\t<b>Statistiche<\/b>\n\t<p id=\"cmplz-tcf-statistics-purpose_legitimate_interests-container\" class=\"cmplz-tcf-container\"><\/p>\n\n\t<b>Marketing<\/b>\n\t<p id=\"cmplz-tcf-marketing-purpose_legitimate_interests-container\" class=\"cmplz-tcf-container\"><\/p>\n\n\t<p class=\"cmplz-subtitle\">7.2.2 Caratteristiche e scopi speciali<\/p>\n\t<div id=\"cmplz-tcf-specialfeatures-wrapper\">\n\t\t<b>Caratteristiche speciali<\/b>\n\t\t<p>Per alcuni degli scopi noi e\/o i nostri partner utilizziamo le seguenti funzioni.<\/p>\n\t\t<p id=\"cmplz-tcf-specialfeatures-container\" class=\"cmplz-tcf-container\"><\/p>\n\t<\/div>\n\n\t<div id=\"cmplz-tcf-specialpurposes-wrapper\">\n\t\t<b>Scopi speciali<\/b>\n\t\t<p>Noi e\/o i nostri partner abbiamo un legittimo interesse per i seguenti due scopi:<\/p>\n\t\t<p id=\"cmplz-tcf-specialpurposes-container\" class=\"cmplz-tcf-container\"><\/p>\n\t<\/div>\n\n\t<div id=\"cmplz-tcf-features-wrapper\">\n\t\t<b>Funzionalit\u00e0<\/b>\n\t\t<p>Per alcuni degli scopi di cui sopra noi e i nostri partner<\/p>\n\t\t<p id=\"cmplz-tcf-features-container\" class=\"cmplz-tcf-container\"><\/p>\n\t<\/div>\n\n\t<p class=\"cmplz-subtitle\">7.2.3 Fornitori<\/p>\n\n\t<div id=\"cmplz-tcf-vendor-container\" class=\"cmplz-tcf-container\"><\/div>\n<\/div>\n<style>#cmplz-tcf-wrapper {display:none;}<\/style>\n<h2>8. Abilitare\/disabilitare e cancellare i cookie<\/h2><p>Puoi usare il tuo browser per cancellare automaticamente o manualmente i cookie. \u00c8 anche possibile specificare che determinati cookie non possono essere piazzati. Un'altra opzione \u00e8 quella di modificare le impostazioni del tuo browser internet in modo da ricevere un messaggio ogni volta che viene inserito un cookie. Per ulteriori informazioni su queste opzioni, consulta le istruzioni nella sezione Guida del tuo browser.<\/p><p>Tieni presente che il nostro sito web potrebbe non funzionare correttamente se tutti i cookie sono disabilitati. Se cancelli i cookie nel tuo browser, essi verranno nuovamente inseriti dopo il consenso fornito quando visiterai nuovamente il nostro sito web.<\/p><h2>9. I tuoi diritti rispetto ai dati personali<\/h2><p>Hai i seguenti diritti relativi ai tuoi dati personali:<\/p><ul>\n                    <li>Hai il diritto di sapere quando i tuoi dati personali sono necessari, cosa succede ad essi, quanto a lungo verranno mantenuti.<\/li>\n                    <li>Diritto di accesso: hai il diritto ad accedere ai tuoi dati personali dei quali siamo a conoscenza.<\/li>\n                    <li>Diritto di rettifica: hai il diritto di completare, correggere, cancellare o bloccare i tuoi dati personali quando lo desideri.<\/li>\n                    <li>Se ci darai il consenso per elaborare i tuoi dati, hai il diritto di revocare questo consenso e di eliminare i tuoi dati personali.<\/li>\n                    <li>Diritto di trasferire i tuoi dati: hai il diritto di richiedere tutti i tuoi dati dal controllore e trasferirli tutti quanti ad un altro controllore.<\/li>\n                    <li>Diritto di obiezione: hai il diritto di obiezione verso il processo dei tuoi dati. Noi rispetteremo questa scelta, a meno che non ci siano delle basi valide per il processo.<\/li>\n                <\/ul><p>Per esercitare questi diritti, non esitare a contattarci. Si prega di fare riferimento ai dettagli di contatto in fondo a questa Cookie Policy. Se hai un reclamo su come gestiamo i tuoi dati, vorremmo sentirti, ma hai anche il diritto di presentare un reclamo all'autorit\u00e0 di vigilanza (l'Autorit\u00e0 per la Protezione dei Dati).<\/p><h2>10. Dettagli contatti<\/h2><p>Per domande e\/o commenti riguardo la Cookie Policy e questa dichiarazione, per favore contattaci usando i seguenti dati di contatto:<\/p><p><span class=\"cmplz-contact-organisation\">Dream-Site e.U.<\/span><br>\n                      <span class=\"cmplz-contact-address\">Effingergasse 22\/2\/10<br \/>\n1160<br \/>\nVienna<\/span><br>\n                      <span class=\"cmplz-contact-country\">Austria<\/span><br>\n                    Sito web: <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/urbexplorer.net\/it\">https:\/\/urbexplorer.net\/it<\/a><\/span><br>\n                    Email: <span class=\"cmplz-contact-email\"><span class=\"cmplz-obfuscate\">ciao@<span class=\"cmplz-fmail-domain\">ex.com<\/span>u&#114;b&#101;x&#112;&#108;orer.n&#101;&#116;<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Numero di telefono: +4314420460<\/span><\/p><p>Questa politica sui cookie \u00e8 stata sincronizzata con <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\" rel=\"noopener\">cookiedatabase.org<\/a> il 6. Maggio 2026.<\/p><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e23370 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"4e23370\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><style>\n  [data-custom-class='body'], [data-custom-class='body'] * {<br \/>          background: transparent !important;<br \/>        }<br \/>[data-custom-class='title'], [data-custom-class='title'] * {<br \/>          font-family: Arial !important;<br \/>font-size: 26px !important;<br \/>color: #000000 !important;<br \/>        }<br \/>[data-custom-class='subtitle'], [data-custom-class='subtitle'] * {<br \/>          font-family: Arial !important;<br \/>color: #595959 !important;<br \/>font-size: 14px !important;<br \/>        }<br \/>[data-custom-class='heading_1'], [data-custom-class='heading_1'] * {<br \/>          font-family: Arial !important;<br \/>font-size: 19px !important;<br \/>color: #000000 !important;<br \/>        }<br \/>[data-custom-class='heading_2'], [data-custom-class='heading_2'] * {<br \/>          font-family: Arial !important;<br \/>font-size: 17px !important;<br \/>color: #000000 !important;<br \/>        }<br \/>[data-custom-class='body_text'], [data-custom-class='body_text'] * {<br \/>          color: #595959 !important;<br \/>font-size: 14px !important;<br \/>font-family: Arial !important;<br \/>        }<br \/>[data-custom-class='link'], [data-custom-class='link'] * {<br \/>          color: #3030F1 !important;<br \/>font-size: 14px !important;<br \/>font-family: Arial !important;<br \/>word-break: break-word !important;<br \/>        }<br \/><\/style><\/p><div data-custom-class=\"body\"><div><span style=\"color: #999999;\"><strong><span style=\"font-size: 26px;\">INFORMATIVA SUI COOKIE<\/span><\/strong><\/span><\/div><div>\u00a0<\/div><div><span style=\"color: #999999;\"><strong><span style=\"font-size: 15px;\">Ultimo aggiornamento 06 aprile 2024<\/span><\/strong><\/span><\/div><div>\u00a0<\/div><div>\u00a0<\/div><div>\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">La presente Informativa sui Cookie spiega come UrbeXplorer (\u201c<strong>Azienda<\/strong>,&#8221; &#8220;<strong>noi<\/strong>,&#8221; &#8220;<strong>noi<\/strong>,\u201d e \u201c<strong>il nostro<\/strong>\u201c) utilizza cookie e tecnologie simili per riconoscerti quando visiti il nostro sito web all'indirizzo \u00a0<\/span><span style=\"font-size: 15px;\"><a style=\"color: #999999;\" href=\"https:\/\/urbexplorer.net\/it\" target=\"_blank\" rel=\"noopener\" data-custom-class=\"link\">http:\/\/www.urbexplorer.net<\/a><\/span><span style=\"font-size: 15px;\"> (&#8220;<strong>Sito web<\/strong>\u201c). Il documento spiega cosa sono queste tecnologie e perch\u00e9 le utilizziamo, nonch\u00e9 i tuoi diritti di controllare l'uso che ne facciamo.<\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">In alcuni casi possiamo utilizzare i cookie per raccogliere informazioni personali o che diventano tali se combinate con altre informazioni.<\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\"><strong>Cosa sono i biscotti?<\/strong><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">I cookie sono piccoli file di dati che vengono inseriti nel tuo computer o dispositivo mobile quando visiti un sito web. I cookie sono ampiamente utilizzati dai proprietari dei siti web per farli funzionare o per renderli pi\u00f9 efficienti, oltre che per fornire informazioni di reportistica.<\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">I cookie impostati dal proprietario del sito web (in questo caso, UrbeXplorer) sono chiamati \u201ccookie di prima parte\u201d. I cookie impostati da soggetti diversi dal proprietario del sito web sono chiamati \u201ccookie di terze parti\u201d. I cookie di terze parti consentono di fornire funzionalit\u00e0 o caratteristiche di terze parti su o attraverso il sito web (ad esempio, pubblicit\u00e0, contenuti interattivi e analisi). Le parti che impostano questi cookie di terze parti possono riconoscere il tuo computer sia quando visita il sito web in questione sia quando visita altri siti web.<\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\"><strong>Perch\u00e9 utilizziamo i cookie?<\/strong><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">Utilizziamo cookie di prima e terza parte per diversi motivi. Alcuni cookie sono necessari per motivi tecnici al funzionamento del nostro sito web e vengono definiti cookie \u201cessenziali\u201d o \u201cstrettamente necessari\u201d. Altri cookie ci permettono di tracciare e indirizzare gli interessi dei nostri utenti per migliorare l'esperienza sulle nostre Propriet\u00e0 Online. Le terze parti utilizzano i cookie attraverso il nostro Sito web per scopi pubblicitari, analitici e di altro tipo. Questo aspetto \u00e8 descritto in modo pi\u00f9 dettagliato di seguito.<\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\"><span id=\"control\"><strong>Come posso controllare i cookie?<\/strong><\/span><\/span><\/span><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\"><span style=\"font-size: 15px;\">Hai il diritto di decidere se accettare o rifiutare i cookie. Puoi esercitare i tuoi diritti sui cookie impostando le tue preferenze nel Cookie Consent Manager. Il Cookie Consent Manager ti permette di selezionare le categorie di cookie che accetti o rifiuti. I cookie essenziali non possono essere rifiutati perch\u00e9 sono strettamente necessari per fornirti i servizi.<\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\"><span style=\"font-size: 15px;\">Il gestore del consenso ai cookie si trova nel banner di notifica e sul nostro sito web. Se scegli di rifiutare i cookie, puoi continuare a utilizzare il nostro sito web, anche se l'accesso ad alcune funzionalit\u00e0 e aree del sito potrebbe essere limitato. Puoi anche impostare o modificare i controlli del tuo browser web per accettare o rifiutare i cookie.<\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><p><span style=\"color: #999999;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\">I tipi specifici di cookie di prima e terza parte utilizzati attraverso il nostro Sito web e le finalit\u00e0 che perseguono sono descritti nella tabella seguente (si prega di notare che i cookie specifici utilizzati possono variare a seconda delle specifiche Propriet\u00e0 online visitate):<\/span><\/span><u><\/u><\/span><\/p><p>Cookie essenziali per il sito web:<\/p><\/div><div><div>\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">Questi cookie sono strettamente necessari per fornirti i servizi disponibili attraverso il nostro sito web e per utilizzare alcune delle sue funzionalit\u00e0, come l'accesso alle aree protette.<\/span><\/span><\/div><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0px 0px 10px; border-radius: 3px; text-align: left;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">rc::a<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scopo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">Utilizzato per tracciare e analizzare il comportamento degli utenti per distinguere gli esseri umani dai bot o dai software automatizzati.<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">www.recaptcha.net<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Servizio:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">reCAPTCHA <a style=\"color: #999999;\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">Visualizza l'informativa sulla privacy del servizio<\/a> <\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">html_local_storage<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">persistente<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0px 0px 10px; border-radius: 3px; text-align: left;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">m<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scopo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">Traccia la sessione dell'utente per Stripe<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">m.stripe.com<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Servizio:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">A strisce <a style=\"color: #999999;\" href=\"https:\/\/stripe.com\/privacy\" target=\"_blank\" rel=\"noopener\">Visualizza l'informativa sulla privacy del servizio<\/a> <\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">server_cookie<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">1 anno 11 mesi 29 giorni<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0px 0px 10px; border-radius: 3px; text-align: left;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">__stripe_mid<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scopo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">Prevenzione e individuazione delle frodi<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">.urbexplorer.net<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Servizio:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">A strisce <a style=\"color: #999999;\" href=\"https:\/\/stripe.com\/en-nl\/privacy\" target=\"_blank\" rel=\"noopener\">Visualizza l'informativa sulla privacy del servizio<\/a> <\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">http_cookie<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">11 mesi 30 giorni<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0px 0px 10px; border-radius: 3px; text-align: left;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">__stripe_sid<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scopo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">Prevenzione e individuazione delle frodi<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">.urbexplorer.net<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Servizio:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">A strisce <a style=\"color: #999999;\" href=\"https:\/\/stripe.com\/en-nl\/privacy\" target=\"_blank\" rel=\"noopener\">Visualizza l'informativa sulla privacy del servizio<\/a> <\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">http_cookie<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">29 minuti<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><\/div><div>\u00a0<\/div><div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\" data-custom-class=\"heading_2\"><span style=\"font-size: 15px;\"><strong><u><br \/>Cookie analitici e di personalizzazione:<\/u><\/strong><\/span><\/span><\/div><p style=\"font-size: 15px; line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">Questi cookie raccolgono informazioni che vengono utilizzate in forma aggregata per aiutarci a capire come viene utilizzato il nostro sito web o l'efficacia delle nostre campagne di marketing, oppure per aiutarci a personalizzare il nostro sito web per te.<\/span><\/span><\/p><div><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0 0 10px; border-radius: 3px;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">_ga<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scopo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">Registra un particolare ID utilizzato per ottenere dati sull'utilizzo del sito web da parte dell'utente.<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">.urbexplorer.net<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Servizio:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">Google Analytics <a style=\"color: #999999;\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">Visualizza l'informativa sulla privacy del servizio<\/a> <\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">http_cookie<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">1 anno 1 mese 4 giorni<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0 0 10px; border-radius: 3px;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">_ga_#<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scopo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">Utilizzato per distinguere i singoli utenti attraverso la designazione di un numero generato in modo casuale come identificativo del cliente, che consente di calcolare le visite e le sessioni.<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">.urbexplorer.net<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Servizio:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">Google Analytics <a style=\"color: #999999;\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">Visualizza l'informativa sulla privacy del servizio<\/a> <\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">http_cookie<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">1 anno 1 mese 4 giorni<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><\/div><\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\" data-custom-class=\"heading_2\"><span style=\"font-size: 15px;\"><strong><u><br \/>Cookie pubblicitari:<\/u><\/strong><\/span><\/span><\/div><div><p style=\"font-size: 15px; line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">Questi cookie vengono utilizzati per rendere i messaggi pubblicitari pi\u00f9 pertinenti per l'utente. Svolgono funzioni come evitare che lo stesso annuncio ricompaia continuamente, garantire che gli annunci vengano visualizzati correttamente per gli inserzionisti e, in alcuni casi, selezionare annunci basati sui tuoi interessi.<\/span><\/span><\/p><div><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0 0 10px; border-radius: 3px;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">IDE<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scopo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">Utilizzato per misurare il tasso di conversione degli annunci presentati all'utente. Scade tra 1,5 anni.<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">.doubleclick.net<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Servizio:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">DoubleClick <a style=\"color: #999999;\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">Visualizza l'informativa sulla privacy del servizio<\/a> <\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">server_cookie<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">1 anno 11 mesi 29 giorni<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0 0 10px; border-radius: 3px;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">test_cookie<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scopo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">Un cookie di sessione utilizzato per verificare se il browser dell'utente supporta i cookie.<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">.doubleclick.net<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Servizio:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">DoubleClick <a style=\"color: #999999;\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">Visualizza l'informativa sulla privacy del servizio<\/a> <\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">server_cookie<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">15 minuti<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><\/div><\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\" data-custom-class=\"heading_2\"><span style=\"font-size: 15px;\"><strong><u><br \/>Biscotti non classificati:<\/u><\/strong><\/span><\/span><\/div><div><p style=\"font-size: 15px; line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">Si tratta di cookie che non sono ancora stati classificati. Stiamo procedendo alla classificazione di questi cookie con l'aiuto dei loro fornitori.<\/span><\/span><\/p><div><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0 0 10px; border-radius: 3px;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">wpEmojiSettingsSupports<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">urbexplorer.net<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">html_session_storage<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">sessione<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0 0 10px; border-radius: 3px;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">cookie s\u00ec-consenso<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">urbexplorer.net<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">http_cookie<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">11 mesi 30 giorni<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><section style=\"width: 100%; border: 1px solid #e6e6e6; margin: 0 0 10px; border-radius: 3px;\" data-custom-class=\"body_text\"><div style=\"padding: 8px 13px; border-bottom: 1px solid #e6e6e6;\"><table><tbody><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Nome:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">rc::h<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Fornitore:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">www.google.com<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Tipo:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">html_local_storage<\/span><\/td><\/tr><tr style=\"font-family: Roboto, Arial; font-size: 12px; line-height: 1.67; margin: 0 0 8px; vertical-align: top;\"><td style=\"text-align: right; color: #19243c; min-width: 80px;\"><span style=\"color: #999999;\">Scade in:<\/span><\/td><td style=\"display: inline-block; margin-left: 5px;\"><span style=\"color: #999999; word-break: break-all;\">persistente<\/span><\/td><\/tr><\/tbody><\/table><\/div><\/section><\/div><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\"><strong>Come posso controllare i cookie sul mio browser?<\/strong><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\" data-custom-class=\"body_text\">Poich\u00e9 le modalit\u00e0 con cui \u00e8 possibile rifiutare i cookie attraverso i controlli del browser web variano da un browser all'altro, \u00e8 consigliabile visitare il menu di aiuto del browser per ulteriori informazioni. Di seguito sono riportate le informazioni su come gestire i cookie sui browser pi\u00f9 diffusi:<\/span><\/div><ul><li style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><a style=\"color: #999999;\" href=\"https:\/\/support.google.com\/chrome\/answer\/95647#zippy=%2Callow-or-block-cookies\" target=\"_blank\" rel=\"noopener noreferrer\">Cromo<\/a><\/span><\/li><li style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><a style=\"color: #999999;\" href=\"https:\/\/support.microsoft.com\/en-us\/windows\/delete-and-manage-cookies-168dab11-0753-043d-7c16-ede5947fc64d\" target=\"_blank\" rel=\"noopener noreferrer\">Internet Explorer<\/a><\/span><\/li><li style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><a style=\"color: #999999;\" href=\"https:\/\/support.mozilla.org\/en-US\/kb\/enhanced-tracking-protection-firefox-desktop?redirectslug=enable-and-disable-cookies-website-preferences&amp;redirectlocale=en-US\" target=\"_blank\" rel=\"noopener noreferrer\">Firefox<\/a><\/span><\/li><li style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><a style=\"color: #999999;\" href=\"https:\/\/support.apple.com\/en-ie\/guide\/safari\/sfri11471\/mac\" target=\"_blank\" rel=\"noopener noreferrer\">Safari<\/a><\/span><\/li><li style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><a style=\"color: #999999;\" href=\"https:\/\/support.microsoft.com\/en-us\/windows\/microsoft-edge-browsing-data-and-privacy-bb8174ba-9d73-dcf2-9b4a-c582b4e640dd\" target=\"_blank\" rel=\"noopener noreferrer\">Bordo<\/a><\/span><\/li><li style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><a style=\"color: #999999;\" href=\"https:\/\/help.opera.com\/en\/latest\/web-preferences\/\" target=\"_blank\" rel=\"noopener noreferrer\">Opera<\/a><\/span><\/li><\/ul><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\" data-custom-class=\"body_text\">Inoltre, la maggior parte delle reti pubblicitarie ti offre la possibilit\u00e0 di rinunciare alla pubblicit\u00e0 mirata. Se vuoi avere maggiori informazioni, visita il sito:<\/span><\/div><ul><li style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><a style=\"color: #999999;\" href=\"http:\/\/www.aboutads.info\/choices\/\" target=\"_blank\" rel=\"noopener noreferrer\">Alleanza per la pubblicit\u00e0 digitale<\/a><\/span><\/li><li style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><a style=\"color: #999999;\" href=\"https:\/\/youradchoices.ca\/\" target=\"_blank\" rel=\"noopener noreferrer\">Alleanza per la pubblicit\u00e0 digitale del Canada<\/a><\/span><\/li><li style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><a style=\"color: #999999;\" href=\"http:\/\/www.youronlinechoices.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Alleanza europea per la pubblicit\u00e0 digitale interattiva<\/a><\/span><\/li><\/ul><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\"><strong>E le altre tecnologie di tracciamento, come i web beacon?<\/strong><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">I cookie non sono l'unico modo\u00a0<span style=\"font-size: 15px;\">per riconoscere o tracciare i visitatori di un sito web. Di tanto in tanto possiamo utilizzare altre tecnologie simili, come i web beacon (talvolta chiamati \u201ctracking pixel\u201d o \u201cclear gif\u201d). Si tratta di piccoli file grafici che contengono un identificatore unico che ci permette di riconoscere quando qualcuno ha visitato il nostro sito web o ha aperto un'e-mail che lo include. Questo ci permette, ad esempio, di monitorare\u00a0<span style=\"font-size: 15px;\">i modelli di traffico degli utenti da una pagina all'altra di un sito web, per consegnare o comunicare con i cookie, per capire se sei arrivato al sito web da una pubblicit\u00e0 online visualizzata su un sito web di terzi, per migliorare le prestazioni del sito e per misurare il successo delle campagne di email marketing. In molti casi, queste tecnologie dipendono dai cookie per funzionare correttamente e quindi il rifiuto dei cookie ne compromette il funzionamento.<\/span><\/span><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\"><strong>Utilizzi i cookie di Flash o i Local Shared Objects?<\/strong><\/span><\/span><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\">I siti web possono anche utilizzare i cosiddetti \u201cFlash Cookies\u201d (noti anche come Local Shared Objects o \u201cLSO\u201d) per, tra le altre cose, raccogliere e memorizzare informazioni sull'utilizzo dei nostri servizi, per la prevenzione delle frodi e per altre operazioni del sito.<\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\">Se non vuoi che i Flash Cookies vengano memorizzati sul tuo computer, puoi regolare le impostazioni del tuo Flash player in modo da bloccare la memorizzazione dei Flash Cookies utilizzando gli strumenti contenuti nel sito web di Flash.\u00a0<\/span><a style=\"color: #999999;\" href=\"http:\/\/www.macromedia.com\/support\/documentation\/en\/flashplayer\/help\/settings_manager07.html\" target=\"_BLANK\" data-custom-class=\"link\" rel=\"noopener\"><span style=\"font-size: 15px;\">Pannello delle impostazioni di archiviazione del sito web<\/span><\/a><span style=\"font-size: 15px;\">. Puoi anche controllare i cookie di Flash accedendo alla sezione\u00a0<\/span><a style=\"color: #999999;\" href=\"http:\/\/www.macromedia.com\/support\/documentation\/en\/flashplayer\/help\/settings_manager03.html\" target=\"_BLANK\" data-custom-class=\"link\" rel=\"noopener\"><span style=\"font-size: 15px;\">Pannello delle impostazioni globali di archiviazione<\/span><\/a><span style=\"font-size: 15px;\">\u00a0e\u00a0<span style=\"font-size: 15px;\">seguendo le istruzioni (che possono includere istruzioni che spiegano, ad esempio, come cancellare i Flash Cookie esistenti (indicati come \u201cinformazioni\u201d sul sito di Macromedia), come impedire che i Flash LSO vengano inseriti nel tuo computer senza che tu lo chieda e (per Flash Player 8 e successivi) come bloccare i Flash Cookie che non vengono forniti dall'operatore della pagina in cui ti trovi in quel momento).<\/span><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\"><span style=\"font-size: 15px;\">Si prega di notare che l'impostazione del Flash Player per limitare o limitare l'accettazione dei Flash Cookies pu\u00f2 ridurre o impedire la funzionalit\u00e0 di alcune applicazioni Flash, incluse, potenzialmente, le applicazioni Flash utilizzate in connessione con i nostri servizi o contenuti online.<\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\"><strong>Pubblicizzi pubblicit\u00e0 mirata?<\/strong><\/span><\/span><\/span><\/span><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\">Le terze parti possono installare dei cookie sul tuo computer o sul tuo dispositivo mobile per pubblicare pubblicit\u00e0 attraverso il nostro sito web. Queste aziende possono utilizzare le informazioni sulle tue visite a questo e ad altri siti web per fornirti pubblicit\u00e0 pertinenti su beni e servizi che potrebbero interessarti. Possono anche utilizzare una tecnologia per misurare l'efficacia degli annunci pubblicitari. A tal fine, possono utilizzare cookie o web beacon per raccogliere informazioni sulle visite dell'utente a questo e ad altri siti al fine di fornire pubblicit\u00e0 pertinenti su beni e servizi di potenziale interesse per l'utente. Le informazioni raccolte attraverso questo processo non consentono a noi o a loro di identificare il tuo nome, i tuoi dati di contatto o altri dettagli che ti identificano direttamente, a meno che tu non scelga di fornirli.<\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\"><span style=\"font-size: 15px;\"><strong>Con quale frequenza aggiornerete la presente Informativa sui cookie?<\/strong><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\"><span style=\"font-size: 15px;\">Potremmo aggiornare\u00a0<span style=\"font-size: 15px;\">questa Informativa sui cookie di tanto in tanto per riflettere, ad esempio, le modifiche ai cookie che utilizziamo o per altri motivi operativi, legali o normativi. Ti invitiamo pertanto a consultare regolarmente la presente Informativa sui cookie per rimanere informato sul nostro utilizzo dei cookie e delle tecnologie correlate.<\/span><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\">La data riportata nella parte superiore della presente Informativa sui cookie indica l'ultimo aggiornamento della stessa.<\/span><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\"><strong>Dove posso ottenere ulteriori informazioni?<\/strong><\/span><\/span><\/span><\/div><div style=\"line-height: 1.5;\">\u00a0<\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\"><span style=\"font-size: 15px;\"><span style=\"font-size: 15px;\">In caso di domande sull'uso dei cookie o di altre tecnologie, contattaci all'indirizzo:<\/span><\/span><\/span><\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\" data-custom-class=\"body_text\">\u00a0<\/span><\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\"><span style=\"font-size: 15px;\">hello@urbexplorer.net<\/span><\/span><\/div><div style=\"line-height: 1.5;\"><span style=\"font-size: 15px; color: #999999;\">__________<\/span><\/div><div style=\"line-height: 1.5;\"><span style=\"color: #999999;\" data-custom-class=\"body_text\"><span style=\"font-size: 15px;\">__________<\/span><\/span><\/div><p>\u00a0<\/p><style>\n      ul {<br \/>        list-style-type: square;<br \/>      }<br \/>      ul > li > ul {<br \/>        list-style-type: circle;<br \/>      }<br \/>      ul > li > ul > li > ul {<br \/>        list-style-type: square;<br \/>      }<br \/>      ol li {<br \/>        font-family: Arial ;<br \/>      }<br \/>    <\/style><p>\u00a0<\/p><\/div><div style=\"color: #595959; font-size: 14px; font-family: Arial; padding-top: 16px;\"><span style=\"color: #999999;\">Questa informativa sui cookie \u00e8 stata creata utilizzando il programma Termly. <a style=\"color: #999999;\" href=\"https:\/\/termly.io\/products\/cookie-consent-manager\/\" target=\"_blank\" rel=\"noopener\">Gestore del consenso ai cookie<\/a>.<\/span><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cookie Policy COOKIE POLICY\u00a0Last updated April 06, 2024\u00a0\u00a0\u00a0This Cookie Policy explains how UrbeXplorer (&#8220;Company,&#8221; &#8220;we,&#8221; &#8220;us,&#8221; and &#8220;our&#8220;) uses cookies and similar technologies to recognize you when you visit our website at \u00a0http:\/\/www.urbexplorer.net (&#8220;Website&#8220;). It explains what these technologies are and why we use them, as well as your rights to control our use of [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1071","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/urbexplorer.net\/it\/wp-json\/wp\/v2\/pages\/1071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbexplorer.net\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/urbexplorer.net\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/urbexplorer.net\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbexplorer.net\/it\/wp-json\/wp\/v2\/comments?post=1071"}],"version-history":[{"count":10,"href":"https:\/\/urbexplorer.net\/it\/wp-json\/wp\/v2\/pages\/1071\/revisions"}],"predecessor-version":[{"id":13797,"href":"https:\/\/urbexplorer.net\/it\/wp-json\/wp\/v2\/pages\/1071\/revisions\/13797"}],"wp:attachment":[{"href":"https:\/\/urbexplorer.net\/it\/wp-json\/wp\/v2\/media?parent=1071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}